{"id":3663,"date":"2022-10-17T11:46:33","date_gmt":"2022-10-17T09:46:33","guid":{"rendered":"https:\/\/www.procosil.com\/partners\/"},"modified":"2025-03-19T09:22:07","modified_gmt":"2025-03-19T08:22:07","slug":"partners","status":"publish","type":"page","link":"https:\/\/www.procosil.com\/en\/partners\/","title":{"rendered":"Partners"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"3663\" class=\"elementor elementor-3663 elementor-689\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-87372bc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"87372bc\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-48af84b\" data-id=\"48af84b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-015d42d elementor-align-left elementor-widget elementor-widget-breadcrumbs\" data-id=\"015d42d\" data-element_type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"breadcrumbs\"><span><span><a href=\"https:\/\/www.procosil.com\/en\/home\/\">Home<\/a><\/span><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9a39f06 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9a39f06\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-55b5296\" data-id=\"55b5296\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0b759c6 elementor-widget elementor-widget-heading\" data-id=\"0b759c6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"color: #145283\">Italian<\/span> Partners<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8ecd4ef elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8ecd4ef\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-baf6cb8\" data-id=\"baf6cb8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2504eca elementor-widget elementor-widget-image\" data-id=\"2504eca\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.procosil.com\/wp-content\/uploads\/2022\/10\/logo_itop_new.svg\" class=\"attachment-full size-full wp-image-735\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af5f866 elementor-widget elementor-widget-heading\" data-id=\"af5f866\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">itop s.p.a. | officine ortopediche<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5989e67 elementor-widget elementor-widget-text-editor\" data-id=\"5989e67\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Italian contact person for ASL\/INAIL practices<\/strong><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5840a67 elementor-widget elementor-widget-text-editor\" data-id=\"5840a67\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Via Prenestina Nuova, 307<br \/>00036 | Palestrina (RM)<br \/>Phone: (+39) 06 95 31 191<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f9637b0 elementor-widget elementor-widget-heading\" data-id=\"f9637b0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\"><a href=\"http:\/\/www.itop.it\" target=\"_blank\">www.itop.it<\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-569580e\" data-id=\"569580e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-79429ae elementor-widget elementor-widget-image\" data-id=\"79429ae\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"939\" height=\"245\" src=\"https:\/\/www.procosil.com\/wp-content\/uploads\/2025\/02\/Bionit_logo.png\" class=\"attachment-full size-full wp-image-6085\" alt=\"\" srcset=\"https:\/\/www.procosil.com\/wp-content\/uploads\/2025\/02\/Bionit_logo.png 939w, https:\/\/www.procosil.com\/wp-content\/uploads\/2025\/02\/Bionit_logo-300x78.png 300w, https:\/\/www.procosil.com\/wp-content\/uploads\/2025\/02\/Bionit_logo-768x200.png 768w\" sizes=\"(max-width: 939px) 100vw, 939px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d7788e elementor-widget elementor-widget-heading\" data-id=\"5d7788e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">BionIT Labs Srl<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1284758 elementor-widget elementor-widget-text-editor\" data-id=\"1284758\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Via Cracovia, 1<br \/>73010 | Soleto LE, Italia<br \/>Phone: (+39) 0836 194 6903<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-988c280 elementor-widget elementor-widget-heading\" data-id=\"988c280\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/bionitlabs.com\/it\/\" target=\"_blank\">www.bionitlabs.com<\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-6ed5102\" data-id=\"6ed5102\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f5376c elementor-widget elementor-widget-image\" data-id=\"2f5376c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.procosil.com\/wp-content\/uploads\/2023\/01\/Logo-IIT-2.svg\" class=\"attachment-full size-full wp-image-5243\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-177c74c elementor-widget elementor-widget-heading\" data-id=\"177c74c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">IIT | Istituto italiano di tecnologia<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-569a7fa elementor-widget elementor-widget-text-editor\" data-id=\"569a7fa\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Via Morego, 30<br \/>16163 | Genova (GE)<br \/>Phone: (+39) 010 28961<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-09d50a4 elementor-widget elementor-widget-heading\" data-id=\"09d50a4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\"><a href=\"http:\/\/www.iit.it\" target=\"_blank\">www.iit.it<\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-eaf5388\" data-id=\"eaf5388\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5a3217b elementor-widget elementor-widget-image\" data-id=\"5a3217b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.procosil.com\/wp-content\/uploads\/2022\/10\/qb-logo.svg\" class=\"attachment-full size-full wp-image-739\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b51925c elementor-widget elementor-widget-heading\" data-id=\"b51925c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">qbrobotics s.r.l.<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45e5cc4 elementor-widget elementor-widget-text-editor\" data-id=\"45e5cc4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Polo Tecnologico di Navacchio<br \/>Via Mario Giuntini, 13<br \/>56021 | Cascina (PI)<br \/>Phone: (+39) 050 09 80 303<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b3f4775 elementor-widget elementor-widget-heading\" data-id=\"b3f4775\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\"><a href=\"http:\/\/qbrobotics.com\" target=\"_blank\">qbrobotics.com<\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f445ef4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f445ef4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-38b2d32\" data-id=\"38b2d32\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c8fbb20 elementor-widget elementor-widget-image\" data-id=\"c8fbb20\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/www.procosil.com\/wp-content\/uploads\/2025\/03\/lolato.jpeg\" class=\"attachment-full size-full wp-image-6758\" alt=\"\" srcset=\"https:\/\/www.procosil.com\/wp-content\/uploads\/2025\/03\/lolato.jpeg 200w, https:\/\/www.procosil.com\/wp-content\/uploads\/2025\/03\/lolato-150x150.jpeg 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d793ce4 elementor-widget elementor-widget-heading\" data-id=\"d793ce4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ortopedia Sanitaria Lolato<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad69ecb elementor-widget elementor-widget-heading\" data-id=\"ad69ecb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.lolato.it\/\" target=\"_blank\">https:\/\/www.lolato.it\/<\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-e0f8bfb\" data-id=\"e0f8bfb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9e0d43a elementor-widget elementor-widget-image\" data-id=\"9e0d43a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1207\" height=\"661\" src=\"https:\/\/www.procosil.com\/wp-content\/uploads\/2025\/03\/ort-piemontese.jpg\" class=\"attachment-full size-full wp-image-6769\" alt=\"\" srcset=\"https:\/\/www.procosil.com\/wp-content\/uploads\/2025\/03\/ort-piemontese.jpg 1207w, https:\/\/www.procosil.com\/wp-content\/uploads\/2025\/03\/ort-piemontese-300x164.jpg 300w, https:\/\/www.procosil.com\/wp-content\/uploads\/2025\/03\/ort-piemontese-1024x561.jpg 1024w, https:\/\/www.procosil.com\/wp-content\/uploads\/2025\/03\/ort-piemontese-768x421.jpg 768w\" sizes=\"(max-width: 1207px) 100vw, 1207px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-09b8cae elementor-widget elementor-widget-heading\" data-id=\"09b8cae\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">ORTOPEDIA PIEMONTESE SNC<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a8ad407 elementor-widget elementor-widget-text-editor\" data-id=\"a8ad407\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tVia Trento 36 <br>13100 Vercelli (VC)<br>Telefono: 0161213333\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-121a356 elementor-widget elementor-widget-heading\" data-id=\"121a356\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/ortopediapiemontese.orthogether.com\/\" target=\"_blank\">ortopediapiemontese.orthogether.com<\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-d276595\" data-id=\"d276595\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-364619a\" data-id=\"364619a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bcbaf82 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bcbaf82\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8d12929\" data-id=\"8d12929\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e22ca83 elementor-widget elementor-widget-heading\" data-id=\"e22ca83\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"color: #145283\">International<\/span> Agents<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5ed9bfe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5ed9bfe\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-dcb5298\" data-id=\"dcb5298\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-84087ba elementor-widget elementor-widget-image\" data-id=\"84087ba\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"229\" src=\"https:\/\/www.procosil.com\/wp-content\/uploads\/2022\/10\/bounce_medical_logo2.png\" class=\"attachment-full size-full wp-image-772\" alt=\"\" srcset=\"https:\/\/www.procosil.com\/wp-content\/uploads\/2022\/10\/bounce_medical_logo2.png 800w, https:\/\/www.procosil.com\/wp-content\/uploads\/2022\/10\/bounce_medical_logo2-300x86.png 300w, https:\/\/www.procosil.com\/wp-content\/uploads\/2022\/10\/bounce_medical_logo2-768x220.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cb71beb elementor-widget elementor-widget-heading\" data-id=\"cb71beb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">bounce medical<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27a599f elementor-widget elementor-widget-text-editor\" data-id=\"27a599f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Agent for the Middle East<br \/><\/strong><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2dadfd8 elementor-widget elementor-widget-text-editor\" data-id=\"2dadfd8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Malek Ounsi <br \/>Phone: (+ 971) 55 715 0806<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-0b9ee10\" data-id=\"0b9ee10\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-16d2da6 elementor-widget elementor-widget-image\" data-id=\"16d2da6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"401\" height=\"93\" src=\"https:\/\/www.procosil.com\/wp-content\/uploads\/2022\/10\/Logo_Symmetry.png\" class=\"attachment-full size-full wp-image-779\" alt=\"\" srcset=\"https:\/\/www.procosil.com\/wp-content\/uploads\/2022\/10\/Logo_Symmetry.png 401w, https:\/\/www.procosil.com\/wp-content\/uploads\/2022\/10\/Logo_Symmetry-300x70.png 300w\" sizes=\"(max-width: 401px) 100vw, 401px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b15b848 elementor-widget elementor-widget-heading\" data-id=\"b15b848\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">simmetry plus<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d0cc15a elementor-widget elementor-widget-text-editor\" data-id=\"d0cc15a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Agent for Asia<br \/><\/strong><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43c7cff elementor-widget elementor-widget-text-editor\" data-id=\"43c7cff\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Roberto Tassinari<br \/>Phone: (+65) 96 18 08 69<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-fc15deb\" data-id=\"fc15deb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ea5a106 elementor-widget elementor-widget-image\" data-id=\"ea5a106\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"117\" height=\"71\" src=\"https:\/\/www.procosil.com\/wp-content\/uploads\/2022\/10\/orthocolor.png\" class=\"attachment-full size-full wp-image-784\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d030e28 elementor-widget elementor-widget-heading\" data-id=\"d030e28\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">orthocolor<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc05c29 elementor-widget elementor-widget-text-editor\" data-id=\"dc05c29\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>European Mandate<br \/><\/strong><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf90c7b elementor-widget elementor-widget-text-editor\" data-id=\"cf90c7b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Claire Letaud<br \/>Phone: (+33) 7 77 77 54 69<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cc1646a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cc1646a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-98e6539\" data-id=\"98e6539\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e39435 elementor-widget elementor-widget-heading\" data-id=\"5e39435\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"color: #145283\">International<\/span> Distributors<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-853ac99 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"853ac99\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6a03739\" data-id=\"6a03739\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-57736e8 elementor-widget elementor-widget-image\" data-id=\"57736e8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.procosil.com\/wp-content\/uploads\/2022\/10\/logo-proteor.svg\" class=\"attachment-full size-full wp-image-842\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b612df6 elementor-widget elementor-widget-heading\" data-id=\"b612df6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Proteor<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b790a89\" data-id=\"b790a89\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-94d96d3 elementor-widget elementor-widget-image\" data-id=\"94d96d3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"250\" src=\"https:\/\/www.procosil.com\/wp-content\/uploads\/2025\/02\/logo-ottobock-orthopedie-services-2022-retina.png\" class=\"attachment-full size-full wp-image-6131\" alt=\"\" srcset=\"https:\/\/www.procosil.com\/wp-content\/uploads\/2025\/02\/logo-ottobock-orthopedie-services-2022-retina.png 750w, https:\/\/www.procosil.com\/wp-content\/uploads\/2025\/02\/logo-ottobock-orthopedie-services-2022-retina-300x100.png 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc315d6 elementor-widget elementor-widget-heading\" data-id=\"fc315d6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">OTTOBOCK RESEAU ORTHOPEDIE ET SERVICE<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-947c95c\" data-id=\"947c95c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5a873a0 elementor-widget elementor-widget-image\" data-id=\"5a873a0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"343\" height=\"147\" src=\"https:\/\/www.procosil.com\/wp-content\/uploads\/2025\/02\/images.png\" class=\"attachment-full size-full wp-image-6118\" alt=\"\" srcset=\"https:\/\/www.procosil.com\/wp-content\/uploads\/2025\/02\/images.png 343w, https:\/\/www.procosil.com\/wp-content\/uploads\/2025\/02\/images-300x129.png 300w\" sizes=\"(max-width: 343px) 100vw, 343px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e720d5b elementor-widget elementor-widget-heading\" data-id=\"e720d5b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">EQWAL GROUP<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4d96d70 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4d96d70\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-256d6bd\" data-id=\"256d6bd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5bd8eea elementor-widget elementor-widget-image\" data-id=\"5bd8eea\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.procosil.com\/wp-content\/uploads\/2022\/10\/Logo-Giglio-orthopedie.svg\" class=\"attachment-full size-full wp-image-835\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-201f31d elementor-widget elementor-widget-heading\" data-id=\"201f31d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">GIGLIO ORTHOPEDIE<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3295639\" data-id=\"3295639\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0478679 elementor-widget elementor-widget-image\" data-id=\"0478679\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.procosil.com\/wp-content\/uploads\/2022\/10\/logo-otech-ticino.svg\" class=\"attachment-full size-full wp-image-809\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-00b1ed6 elementor-widget elementor-widget-heading\" data-id=\"00b1ed6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"> O-TECH TICINO SA<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-0bfbb50\" data-id=\"0bfbb50\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34c169e elementor-widget elementor-widget-image\" data-id=\"34c169e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"543\" src=\"https:\/\/www.procosil.com\/wp-content\/uploads\/2022\/10\/Logo-ATC_low.jpg\" class=\"attachment-full size-full wp-image-805\" alt=\"\" srcset=\"https:\/\/www.procosil.com\/wp-content\/uploads\/2022\/10\/Logo-ATC_low.jpg 800w, https:\/\/www.procosil.com\/wp-content\/uploads\/2022\/10\/Logo-ATC_low-300x204.jpg 300w, https:\/\/www.procosil.com\/wp-content\/uploads\/2022\/10\/Logo-ATC_low-768x521.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af79255 elementor-widget elementor-widget-heading\" data-id=\"af79255\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"> ADVANCED TECHNOLOGY COMPANY<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3052992 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3052992\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6a8aa58\" data-id=\"6a8aa58\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-64f1f18 elementor-widget elementor-widget-image\" data-id=\"64f1f18\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"90\" src=\"https:\/\/www.procosil.com\/wp-content\/uploads\/2022\/10\/Orthomedics-logo.jpg\" class=\"attachment-full size-full wp-image-2281\" alt=\"\" srcset=\"https:\/\/www.procosil.com\/wp-content\/uploads\/2022\/10\/Orthomedics-logo.jpg 800w, https:\/\/www.procosil.com\/wp-content\/uploads\/2022\/10\/Orthomedics-logo-300x34.jpg 300w, https:\/\/www.procosil.com\/wp-content\/uploads\/2022\/10\/Orthomedics-logo-768x86.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c2fc3a1 elementor-widget elementor-widget-heading\" data-id=\"c2fc3a1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">ORTHOMEDICS<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-67eae60\" data-id=\"67eae60\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab7894f elementor-widget elementor-widget-image\" data-id=\"ab7894f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"245\" src=\"https:\/\/www.procosil.com\/wp-content\/uploads\/2022\/10\/gobionic-logo_low.jpg\" class=\"attachment-full size-full wp-image-801\" alt=\"\" srcset=\"https:\/\/www.procosil.com\/wp-content\/uploads\/2022\/10\/gobionic-logo_low.jpg 800w, https:\/\/www.procosil.com\/wp-content\/uploads\/2022\/10\/gobionic-logo_low-300x92.jpg 300w, https:\/\/www.procosil.com\/wp-content\/uploads\/2022\/10\/gobionic-logo_low-768x235.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4442304 elementor-widget elementor-widget-heading\" data-id=\"4442304\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">GO BIONIC PED, LDA<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3b47af8\" data-id=\"3b47af8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-79dc2ef elementor-widget elementor-widget-image\" data-id=\"79dc2ef\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"240\" src=\"https:\/\/www.procosil.com\/wp-content\/uploads\/2022\/10\/logo-btc_low-1.png\" class=\"attachment-full size-full wp-image-821\" alt=\"\" srcset=\"https:\/\/www.procosil.com\/wp-content\/uploads\/2022\/10\/logo-btc_low-1.png 800w, https:\/\/www.procosil.com\/wp-content\/uploads\/2022\/10\/logo-btc_low-1-300x90.png 300w, https:\/\/www.procosil.com\/wp-content\/uploads\/2022\/10\/logo-btc_low-1-768x230.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed58fa3 elementor-widget elementor-widget-heading\" data-id=\"ed58fa3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">BERTRAND TOURRET COUDERC | ORTHOP\u00c9DISTE-ORTH\u00c9SISTE<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-beffe9d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"beffe9d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2bc8637\" data-id=\"2bc8637\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c1a8aea elementor-widget elementor-widget-image\" data-id=\"c1a8aea\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"491\" height=\"40\" src=\"https:\/\/www.procosil.com\/wp-content\/uploads\/2023\/01\/logo-celtis-pharm.png\" class=\"attachment-full size-full wp-image-3527\" alt=\"\" srcset=\"https:\/\/www.procosil.com\/wp-content\/uploads\/2023\/01\/logo-celtis-pharm.png 491w, https:\/\/www.procosil.com\/wp-content\/uploads\/2023\/01\/logo-celtis-pharm-300x24.png 300w\" sizes=\"(max-width: 491px) 100vw, 491px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f0abd0 elementor-widget elementor-widget-heading\" data-id=\"6f0abd0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">CELTIS PHARM <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-8df5424\" data-id=\"8df5424\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ffae11 elementor-widget elementor-widget-image\" data-id=\"6ffae11\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"340\" height=\"120\" src=\"https:\/\/www.procosil.com\/wp-content\/uploads\/2023\/01\/orthopedietechniek.jpg\" class=\"attachment-full size-full wp-image-3532\" alt=\"\" srcset=\"https:\/\/www.procosil.com\/wp-content\/uploads\/2023\/01\/orthopedietechniek.jpg 340w, https:\/\/www.procosil.com\/wp-content\/uploads\/2023\/01\/orthopedietechniek-300x106.jpg 300w\" sizes=\"(max-width: 340px) 100vw, 340px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1728f7e elementor-widget elementor-widget-heading\" data-id=\"1728f7e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">RUNDAM ORTHOPEDIE TECHNIEK<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-61c1080\" data-id=\"61c1080\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c2f301b elementor-widget elementor-widget-image\" data-id=\"c2f301b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"225\" src=\"https:\/\/www.procosil.com\/wp-content\/uploads\/2025\/02\/orthopedic-center-malta.png\" class=\"attachment-full size-full wp-image-6137\" alt=\"\" srcset=\"https:\/\/www.procosil.com\/wp-content\/uploads\/2025\/02\/orthopedic-center-malta.png 225w, https:\/\/www.procosil.com\/wp-content\/uploads\/2025\/02\/orthopedic-center-malta-150x150.png 150w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7435a8a elementor-widget elementor-widget-heading\" data-id=\"7435a8a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">ORTHOPAEDIC CENTRE MALTA<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e673cf9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e673cf9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e0c833f\" data-id=\"e0c833f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-27b3072 elementor-widget elementor-widget-heading\" data-id=\"27b3072\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"color: #145283\">All<\/span> our Partners<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2b172c6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2b172c6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f2e8506\" data-id=\"f2e8506\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-84f0392 mappa_store elementor-widget elementor-widget-shortcode\" data-id=\"84f0392\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><style>\r\n\t#wpsl-stores .wpsl-store-thumb {height:45px !important; width:45px !important;}\r\n\t#wpsl-stores, #wpsl-direction-details, #wpsl-gmap {height:450px !important;}\r\n\t#wpsl-gmap .wpsl-info-window {max-width:250px !important;}\r\n\t.wpsl-input label, #wpsl-radius label, #wpsl-category label {width:95px;}\r\n\t#wpsl-search-input ,#wpsl-category .wpsl-dropdown {width:250px;}\r\n<\/style>\r\n<div id=\"wpsl-wrap\">\r\n\t<div class=\"wpsl-search wpsl-clearfix \">\r\n\t\t<div id=\"wpsl-search-wrap\">\r\n\t\t\t<form autocomplete=\"off\">\r\n\t\t\t<div class=\"wpsl-input\">\r\n\t\t\t\t<div><label for=\"wpsl-search-input\">Your location<\/label><\/div>\r\n\t\t\t\t<input id=\"wpsl-search-input\" type=\"text\" value=\"\" name=\"wpsl-search-input\" placeholder=\"\" aria-required=\"true\" \/>\r\n\t\t\t<\/div>\r\n<div id=\"wpsl-category\">\r\n<label for=\"wpsl-category-list\">Category<\/label>\r\n<select  name='wpsl-category' id='wpsl-category-list' class='wpsl-dropdown'>\n\t<option value='0'>Any<\/option>\n\t<option class=\"level-0\" value=\"28\">Distributori Internazionali<\/option>\n\t<option class=\"level-0\" value=\"26\">Partners Italiani<\/option>\n<\/select>\n<\/div>\r\n\t\t\t\t<div class=\"wpsl-search-btn-wrap\"><input id=\"wpsl-search-btn\" type=\"submit\" value=\"Search\"><\/div>\r\n\t\t<\/form>\r\n\t\t<\/div>\r\n\t<\/div>\r\n\t<div id=\"wpsl-gmap\" class=\"wpsl-gmap-canvas\"><\/div>\r\n\t<div id=\"wpsl-result-list\">\r\n\t\t<div id=\"wpsl-stores\" >\r\n\t\t\t<ul><\/ul>\r\n\t\t<\/div>\r\n\t\t<div id=\"wpsl-direction-details\">\r\n\t\t\t<ul><\/ul>\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/div>\r\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Italian Partners itop s.p.a. | officine ortopediche Italian contact person for ASL\/INAIL practices Via Prenestina Nuova, 30700036 | Palestrina (RM)Phone: (+39) 06 95 31 191 www.itop.it BionIT Labs Srl Via Cracovia, 173010 | Soleto LE, ItaliaPhone: (+39) 0836 194 6903 www.bionitlabs.com IIT | Istituto italiano di tecnologia Via Morego, 3016163 | Genova (GE)Phone: (+39) 010 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3663","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Partners - Procosil<\/title>\n<meta name=\"description\" content=\"Italian and international partners, agencies and distributors, find out who we work with\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.procosil.com\/en\/partners\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Partners - Procosil\" \/>\n<meta property=\"og:description\" content=\"Italian and international partners, agencies and distributors, find out who we work with\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.procosil.com\/en\/partners\/\" \/>\n<meta property=\"og:site_name\" content=\"Procosil\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-19T08:22:07+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.procosil.com\/en\/partners\/\",\"url\":\"https:\/\/www.procosil.com\/en\/partners\/\",\"name\":\"Partners - Procosil\",\"isPartOf\":{\"@id\":\"https:\/\/www.procosil.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.procosil.com\/en\/partners\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.procosil.com\/en\/partners\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.procosil.com\/wp-content\/uploads\/2022\/10\/logo_itop_new.svg\",\"datePublished\":\"2022-10-17T09:46:33+00:00\",\"dateModified\":\"2025-03-19T08:22:07+00:00\",\"description\":\"Italian and international partners, agencies and distributors, find out who we work with\",\"breadcrumb\":{\"@id\":\"https:\/\/www.procosil.com\/en\/partners\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.procosil.com\/en\/partners\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.procosil.com\/en\/partners\/#primaryimage\",\"url\":\"https:\/\/www.procosil.com\/wp-content\/uploads\/2022\/10\/logo_itop_new.svg\",\"contentUrl\":\"https:\/\/www.procosil.com\/wp-content\/uploads\/2022\/10\/logo_itop_new.svg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.procosil.com\/en\/partners\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.procosil.com\/en\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Partners\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.procosil.com\/en\/#website\",\"url\":\"https:\/\/www.procosil.com\/en\/\",\"name\":\"Procosil\",\"description\":\"Hightech Prosthesis\",\"publisher\":{\"@id\":\"https:\/\/www.procosil.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.procosil.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.procosil.com\/en\/#organization\",\"name\":\"Procosil\",\"url\":\"https:\/\/www.procosil.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.procosil.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.procosil.com\/wp-content\/uploads\/2022\/10\/Logo-Ufficiale_RGB-1.svg\",\"contentUrl\":\"https:\/\/www.procosil.com\/wp-content\/uploads\/2022\/10\/Logo-Ufficiale_RGB-1.svg\",\"caption\":\"Procosil\"},\"image\":{\"@id\":\"https:\/\/www.procosil.com\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Partners - Procosil","description":"Italian and international partners, agencies and distributors, find out who we work with","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.procosil.com\/en\/partners\/","og_locale":"en_US","og_type":"article","og_title":"Partners - Procosil","og_description":"Italian and international partners, agencies and distributors, find out who we work with","og_url":"https:\/\/www.procosil.com\/en\/partners\/","og_site_name":"Procosil","article_modified_time":"2025-03-19T08:22:07+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.procosil.com\/en\/partners\/","url":"https:\/\/www.procosil.com\/en\/partners\/","name":"Partners - Procosil","isPartOf":{"@id":"https:\/\/www.procosil.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.procosil.com\/en\/partners\/#primaryimage"},"image":{"@id":"https:\/\/www.procosil.com\/en\/partners\/#primaryimage"},"thumbnailUrl":"https:\/\/www.procosil.com\/wp-content\/uploads\/2022\/10\/logo_itop_new.svg","datePublished":"2022-10-17T09:46:33+00:00","dateModified":"2025-03-19T08:22:07+00:00","description":"Italian and international partners, agencies and distributors, find out who we work with","breadcrumb":{"@id":"https:\/\/www.procosil.com\/en\/partners\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.procosil.com\/en\/partners\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.procosil.com\/en\/partners\/#primaryimage","url":"https:\/\/www.procosil.com\/wp-content\/uploads\/2022\/10\/logo_itop_new.svg","contentUrl":"https:\/\/www.procosil.com\/wp-content\/uploads\/2022\/10\/logo_itop_new.svg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.procosil.com\/en\/partners\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.procosil.com\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Partners"}]},{"@type":"WebSite","@id":"https:\/\/www.procosil.com\/en\/#website","url":"https:\/\/www.procosil.com\/en\/","name":"Procosil","description":"Hightech Prosthesis","publisher":{"@id":"https:\/\/www.procosil.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.procosil.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.procosil.com\/en\/#organization","name":"Procosil","url":"https:\/\/www.procosil.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.procosil.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.procosil.com\/wp-content\/uploads\/2022\/10\/Logo-Ufficiale_RGB-1.svg","contentUrl":"https:\/\/www.procosil.com\/wp-content\/uploads\/2022\/10\/Logo-Ufficiale_RGB-1.svg","caption":"Procosil"},"image":{"@id":"https:\/\/www.procosil.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.procosil.com\/en\/wp-json\/wp\/v2\/pages\/3663","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.procosil.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.procosil.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.procosil.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.procosil.com\/en\/wp-json\/wp\/v2\/comments?post=3663"}],"version-history":[{"count":10,"href":"https:\/\/www.procosil.com\/en\/wp-json\/wp\/v2\/pages\/3663\/revisions"}],"predecessor-version":[{"id":7038,"href":"https:\/\/www.procosil.com\/en\/wp-json\/wp\/v2\/pages\/3663\/revisions\/7038"}],"wp:attachment":[{"href":"https:\/\/www.procosil.com\/en\/wp-json\/wp\/v2\/media?parent=3663"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}